{"id":30951,"date":"2019-04-26T07:00:18","date_gmt":"2019-04-26T06:00:18","guid":{"rendered":"https:\/\/www.tecnomagazine.it\/tech\/?p=30951"},"modified":"2023-09-07T15:36:44","modified_gmt":"2023-09-07T14:36:44","slug":"cosa-bisogna-fare-per-configurare-il-modem-di-fastweb","status":"publish","type":"post","link":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/","title":{"rendered":"Cosa configurare il modem di Fastweb"},"content":{"rendered":"<div class=\"4032636bd480207a9641f06a0353772e\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--COOKIE_POLICY_BEGIN-->\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Tecnomagine Grande -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4884298544160548\"\r\n     data-ad-slot=\"6528327022\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<!--COOKIE_POLICY_END-->\n<\/div>\n<p>Prima di iniziare a\u00a0<strong>configurare il modem di Fastweb<\/strong>\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il tipo di\u00a0<strong>rete Fastweb<\/strong>\u00a0da cui si \u00e8 serviti. Nel caso in cui si disponga di una connessione Adsl, occorre un modem che sia in grado di supportare lo standard Adsl2+. Viceversa, c&#8217;\u00e8 bisogno di un modem che possa supportare lo standard Vdsl2 quando la connessione \u00e8 di tipo Fttc.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-30952 size-medium\" src=\"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb-500x284.jpg\" alt=\"\" width=\"500\" height=\"284\" srcset=\"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb-500x284.jpg 500w, https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb-768x436.jpg 768w, https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg 1000w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/>\r\n<div class=\"4032636bd480207a9641f06a0353772e\" data-index=\"1\" style=\"float: none; margin:10px 0 10px 0; text-align:center;\">\n<!--COOKIE_POLICY_BEGIN-->\r\n<script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\r\n<!-- Tecnomagine Grande -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-4884298544160548\"\r\n     data-ad-slot=\"6528327022\"\r\n     data-ad-format=\"auto\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n<!--COOKIE_POLICY_END-->\n<\/div>\n\r\n<\/p>\n<h2>Come iniziare<\/h2>\n<p>Dopo aver accertato che<strong>\u00a0il router \u00e8 compatibile con la rete Fastweb<\/strong>, \u00e8 necessario accendere il dispositivo e connetterlo come necessario:\u00a0<strong><a href=\"https:\/\/www.negozi.fastweb.it\/it\/modem-fastweb-fastgate\/\" target=\"_blank\" rel=\"noopener\"><u>il modem Fastweb per fibra ottica<\/u><\/a><\/strong>\u00a0va collegato con il terminale ottico che \u00e8 stato installato dal tecnico, mentre in caso di connessione Adsl bisogna fare riferimento alla presa del telefono. Per le connessioni in fibra, il router deve essere collegato con la terminazione ottica Ont: questa sigla \u00e8 l&#8217;acronimo di\u00a0<strong>Optical Network Terminal<\/strong>, e indica una scatola di piccole dimensioni che serve a far da ponte tra il router stesso e la fibra ottica. A tale scopo ci si pu\u00f2 servire di un cavo di rete Ethernet che sia almeno di Categoria 5e, che deve essere inserito all&#8217;interno della<strong>\u00a0porta WAN Ethernet<\/strong>\u00a0del modem. Quest&#8217;ultimo, infine, con un cavo di rete Ethernet normale va collegato anche a un notebook o a un computer fisso.<\/p>\n<h2>Cosa fare dopo aver collegato i cavi<\/h2>\n<p>Esauriti i passaggi relativi ai\u00a0<strong>collegamenti dei cavi<\/strong>, si pu\u00f2 procedere connettendosi con il router dal pc, in modo tale che esso possa essere configurato con i parametri necessari per la rete da cui si \u00e8 serviti. A tale scopo occorre eseguire l&#8217;accesso al pannello di controllo del router, e per riuscirci \u00e8 sufficiente aprire una finestra del router e, nella barra in cui sono presenti gli URL, digitare l&#8217;<strong>indirizzo IP del router<\/strong>. Questo indirizzo \u00e8 riportato, di solito, nella parte posteriore del modem o comunque sul suo manuale utente.<\/p>\n<h2>La configurazione del router<\/h2>\n<p>Nella sezione dedicata alla configurazione del router si apre la scheda con i\u00a0<strong>parametri di rete<\/strong>\u00a0e si agisce sulla base delle indicazioni fornite da Fastweb. I parametri cambiano a seconda che si abbia un router Adsl o un router Fttc: nel primo caso, per esempio, l&#8217;incapsulamento \u00e8 LLC, mentre nel secondo caso \u00e8 PTM. Per gli abbonati a Fastweb \u00e8 disponibile una\u00a0<strong>guida alla configurazione<\/strong>\u00a0che contiene le istruzioni da seguire per ognuno dei 15 modem pi\u00f9 diffusi alternativi al FastGate: occorre iscriversi a MyFastPage per consultarla.<\/p>\n<h2>Non c&#8217;\u00e8 bisogno di un modem Fastweb<\/h2>\n<p>Non \u00e8 necessario il modem di Fastweb, infatti, per connettersi a Internet usando i servizi di questo operatore. Il merito \u00e8 della<strong>\u00a0delibera dell&#8217;Agcom<\/strong>, l&#8217;Autorit\u00e0 Garante delle Comunicazioni, denominata &#8220;Modem Libero&#8221;, per effetto della quale non si \u00e8 obbligati a impiegare il modem che viene messo a disposizione dal fornitore del servizio Internet in<strong>\u00a0comodato d&#8217;uso<\/strong>, ma si \u00e8 liberi di utilizzare il router che si desidera. In questo modo si spende di meno e si \u00e8 avvantaggiati sul piano pratico.<\/p>\n<h2>I consigli per i clienti di Fastweb<\/h2>\n<p>Un cliente di Fastweb che abbia acquistato un abbonamento Adsl o Fttc pu\u00f2 usare qualsiasi modem, anche se non si tratta del\u00a0<strong>FastGate<\/strong>. Qualche problema in pi\u00f9, tuttavia, potrebbe sorgere per chi dispone di un abbonamento Ftth, visto che in questo caso potrebbe essere difficile individuare un modem per fibra che non sia un FastGate. Per saperne di pi\u00f9, e per ottenere tutte le informazioni utili in proposito, si pu\u00f2 sempre consultare il servizio clienti dell&#8217;operatore. La\u00a0<strong>differenza tra Fttc e Ftth<\/strong>\u00a0\u00e8 che nel primo caso la fibra giunge fino all&#8217;armadietto in strada &#8211; Fiber to the cabinet &#8211; mentre nel secondo caso arriva fino al portone di casa &#8211; Fiber to the home -.<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi<\/p>\n","protected":false},"author":39,"featured_media":30952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-30951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cosa configurare il modem di Fastweb - TecnoMagazine<\/title>\n<meta name=\"description\" content=\"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosa configurare il modem di Fastweb - TecnoMagazine\" \/>\n<meta property=\"og:description\" content=\"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/\" \/>\n<meta property=\"og:site_name\" content=\"TecnoMagazine\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-26T06:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T14:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Federico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tecnomagazineit\" \/>\n<meta name=\"twitter:site\" content=\"@tecnomagazineit\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/\"},\"author\":{\"name\":\"Federico\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/#\\\/schema\\\/person\\\/40062887af65099e6b2972a5eef6ee32\"},\"headline\":\"Cosa configurare il modem di Fastweb\",\"datePublished\":\"2019-04-26T06:00:18+00:00\",\"dateModified\":\"2023-09-07T14:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/\"},\"wordCount\":620,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/wp-content\\\/uploads\\\/4183-modem-Fastweb.jpg\",\"articleSection\":[\"Curiosit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/\",\"url\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/\",\"name\":\"Cosa configurare il modem di Fastweb - TecnoMagazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/wp-content\\\/uploads\\\/4183-modem-Fastweb.jpg\",\"datePublished\":\"2019-04-26T06:00:18+00:00\",\"dateModified\":\"2023-09-07T14:36:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/#\\\/schema\\\/person\\\/40062887af65099e6b2972a5eef6ee32\"},\"description\":\"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/wp-content\\\/uploads\\\/4183-modem-Fastweb.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/wp-content\\\/uploads\\\/4183-modem-Fastweb.jpg\",\"width\":1000,\"height\":568},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/30951\\\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosa configurare il modem di Fastweb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/#website\",\"url\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/\",\"name\":\"TecnoMagazine\",\"description\":\"Approfondimenti, Tendenze e Innovazioni nel Vasto Universo dell&#039;Informatica e della Tecnologia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/#\\\/schema\\\/person\\\/40062887af65099e6b2972a5eef6ee32\",\"name\":\"Federico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g\",\"caption\":\"Federico\"},\"url\":\"https:\\\/\\\/www.tecnomagazine.it\\\/tech\\\/author\\\/federico\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cosa configurare il modem di Fastweb - TecnoMagazine","description":"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/","og_locale":"it_IT","og_type":"article","og_title":"Cosa configurare il modem di Fastweb - TecnoMagazine","og_description":"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il","og_url":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/","og_site_name":"TecnoMagazine","article_published_time":"2019-04-26T06:00:18+00:00","article_modified_time":"2023-09-07T14:36:44+00:00","og_image":[{"width":1000,"height":568,"url":"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg","type":"image\/jpeg"}],"author":"Federico","twitter_card":"summary_large_image","twitter_creator":"@tecnomagazineit","twitter_site":"@tecnomagazineit","twitter_misc":{"Scritto da":"Federico","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#article","isPartOf":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/"},"author":{"name":"Federico","@id":"https:\/\/www.tecnomagazine.it\/tech\/#\/schema\/person\/40062887af65099e6b2972a5eef6ee32"},"headline":"Cosa configurare il modem di Fastweb","datePublished":"2019-04-26T06:00:18+00:00","dateModified":"2023-09-07T14:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/"},"wordCount":620,"commentCount":0,"image":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg","articleSection":["Curiosit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/","url":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/","name":"Cosa configurare il modem di Fastweb - TecnoMagazine","isPartOf":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#primaryimage"},"image":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg","datePublished":"2019-04-26T06:00:18+00:00","dateModified":"2023-09-07T14:36:44+00:00","author":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/#\/schema\/person\/40062887af65099e6b2972a5eef6ee32"},"description":"Prima di iniziare a\u00a0configurare il modem di Fastweb\u00a0\u00e8 necessario assicurarsi che il modem router che si \u00e8 intenzionati a utilizzare sia compatibile con il","breadcrumb":{"@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#primaryimage","url":"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg","contentUrl":"https:\/\/www.tecnomagazine.it\/tech\/wp-content\/uploads\/4183-modem-Fastweb.jpg","width":1000,"height":568},{"@type":"BreadcrumbList","@id":"https:\/\/www.tecnomagazine.it\/tech\/30951\/cosa-bisogna-fare-per-configurare-il-modem-di-fastweb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tecnomagazine.it\/tech\/"},{"@type":"ListItem","position":2,"name":"Cosa configurare il modem di Fastweb"}]},{"@type":"WebSite","@id":"https:\/\/www.tecnomagazine.it\/tech\/#website","url":"https:\/\/www.tecnomagazine.it\/tech\/","name":"TecnoMagazine","description":"Approfondimenti, Tendenze e Innovazioni nel Vasto Universo dell&#039;Informatica e della Tecnologia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tecnomagazine.it\/tech\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.tecnomagazine.it\/tech\/#\/schema\/person\/40062887af65099e6b2972a5eef6ee32","name":"Federico","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d768466ef8e45d61fdea884dcee823d4c1e7caba27ba5c14e87f0f29166ab03e?s=96&d=blank&r=g","caption":"Federico"},"url":"https:\/\/www.tecnomagazine.it\/tech\/author\/federico\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/posts\/30951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/comments?post=30951"}],"version-history":[{"count":0,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/posts\/30951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/media\/30952"}],"wp:attachment":[{"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/media?parent=30951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/categories?post=30951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tecnomagazine.it\/tech\/wp-json\/wp\/v2\/tags?post=30951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}